{"id":9757,"date":"2025-04-09T11:16:26","date_gmt":"2025-04-09T11:16:26","guid":{"rendered":"https:\/\/www.av-messe.de\/uber-uns\/"},"modified":"2026-02-09T07:25:17","modified_gmt":"2026-02-09T07:25:17","slug":"about-us","status":"publish","type":"page","link":"https:\/\/www.av-messe.de\/en\/about-us\/","title":{"rendered":"About us"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-9757","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About us - ATV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.av-messe.de\/en\/about-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About us - ATV\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.av-messe.de\/en\/about-us\/\" \/>\n<meta property=\"og:site_name\" content=\"ATV\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T07:25:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.av-messe.de\/en\/about-us\/\",\"url\":\"https:\/\/www.av-messe.de\/en\/about-us\/\",\"name\":\"About us - ATV\",\"isPartOf\":{\"@id\":\"https:\/\/www.av-messe.de\/en\/#website\"},\"datePublished\":\"2025-04-09T11:16:26+00:00\",\"dateModified\":\"2026-02-09T07:25:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.av-messe.de\/en\/about-us\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.av-messe.de\/en\/about-us\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.av-messe.de\/en\/about-us\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.av-messe.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.av-messe.de\/en\/#website\",\"url\":\"https:\/\/www.av-messe.de\/en\/\",\"name\":\"ATV\",\"description\":\"Messebau Hannover\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.av-messe.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About us - ATV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.av-messe.de\/en\/about-us\/","og_locale":"en_US","og_type":"article","og_title":"About us - ATV","og_url":"https:\/\/www.av-messe.de\/en\/about-us\/","og_site_name":"ATV","article_modified_time":"2026-02-09T07:25:17+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.av-messe.de\/en\/about-us\/","url":"https:\/\/www.av-messe.de\/en\/about-us\/","name":"About us - ATV","isPartOf":{"@id":"https:\/\/www.av-messe.de\/en\/#website"},"datePublished":"2025-04-09T11:16:26+00:00","dateModified":"2026-02-09T07:25:17+00:00","breadcrumb":{"@id":"https:\/\/www.av-messe.de\/en\/about-us\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.av-messe.de\/en\/about-us\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.av-messe.de\/en\/about-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.av-messe.de\/en\/"},{"@type":"ListItem","position":2,"name":"About us"}]},{"@type":"WebSite","@id":"https:\/\/www.av-messe.de\/en\/#website","url":"https:\/\/www.av-messe.de\/en\/","name":"ATV","description":"Messebau Hannover","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.av-messe.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.av-messe.de\/en\/wp-json\/wp\/v2\/pages\/9757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.av-messe.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.av-messe.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.av-messe.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.av-messe.de\/en\/wp-json\/wp\/v2\/comments?post=9757"}],"version-history":[{"count":9,"href":"https:\/\/www.av-messe.de\/en\/wp-json\/wp\/v2\/pages\/9757\/revisions"}],"predecessor-version":[{"id":9924,"href":"https:\/\/www.av-messe.de\/en\/wp-json\/wp\/v2\/pages\/9757\/revisions\/9924"}],"wp:attachment":[{"href":"https:\/\/www.av-messe.de\/en\/wp-json\/wp\/v2\/media?parent=9757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}